{"id":213,"count":1,"description":"","link":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/","name":"Exklusives \u00d6l","slug":"exklusives-ol","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exklusives \u00d6l archivos - Grenade Olive Oil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exklusives \u00d6l archivos - Grenade Olive Oil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/\" \/>\n<meta property=\"og:site_name\" content=\"Grenade Olive Oil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/blog\\\/tag\\\/exklusives-ol\\\/\",\"url\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/blog\\\/tag\\\/exklusives-ol\\\/\",\"name\":\"Exklusives \u00d6l archivos - Grenade Olive Oil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/blog\\\/tag\\\/exklusives-ol\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/blog\\\/tag\\\/exklusives-ol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exklusives \u00d6l\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/\",\"name\":\"Grenade Olive Oil\",\"description\":\"Green Olive Oil\",\"publisher\":{\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/#organization\",\"name\":\"Grande Olive Oil\",\"url\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grenadeoliveoil.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/aceite-verde-grenade-olive-oil.jpg\",\"contentUrl\":\"https:\\\/\\\/grenadeoliveoil.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/aceite-verde-grenade-olive-oil.jpg\",\"width\":150,\"height\":75,\"caption\":\"Grande Olive Oil\"},\"image\":{\"@id\":\"https:\\\/\\\/grenadeoliveoil.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exklusives \u00d6l archivos - Grenade Olive Oil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/","og_locale":"de_DE","og_type":"article","og_title":"Exklusives \u00d6l archivos - Grenade Olive Oil","og_url":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/","og_site_name":"Grenade Olive Oil","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/","url":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/","name":"Exklusives \u00d6l archivos - Grenade Olive Oil","isPartOf":{"@id":"https:\/\/grenadeoliveoil.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/grenadeoliveoil.com\/de\/blog\/tag\/exklusives-ol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grenadeoliveoil.com\/de\/"},{"@type":"ListItem","position":2,"name":"Exklusives \u00d6l"}]},{"@type":"WebSite","@id":"https:\/\/grenadeoliveoil.com\/de\/#website","url":"https:\/\/grenadeoliveoil.com\/de\/","name":"Grenade Olive Oil","description":"Green Olive Oil","publisher":{"@id":"https:\/\/grenadeoliveoil.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grenadeoliveoil.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/grenadeoliveoil.com\/de\/#organization","name":"Grande Olive Oil","url":"https:\/\/grenadeoliveoil.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/grenadeoliveoil.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/grenadeoliveoil.com\/wp-content\/uploads\/2021\/11\/aceite-verde-grenade-olive-oil.jpg","contentUrl":"https:\/\/grenadeoliveoil.com\/wp-content\/uploads\/2021\/11\/aceite-verde-grenade-olive-oil.jpg","width":150,"height":75,"caption":"Grande Olive Oil"},"image":{"@id":"https:\/\/grenadeoliveoil.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/grenadeoliveoil.com\/de\/wp-json\/wp\/v2\/tags\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenadeoliveoil.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/grenadeoliveoil.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/grenadeoliveoil.com\/de\/wp-json\/wp\/v2\/posts?tags=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}